{"id":230,"date":"2024-02-17T01:35:13","date_gmt":"2024-02-17T01:35:13","guid":{"rendered":"https:\/\/sgh.com.co\/?post_type=ignition-service&#038;p=230"},"modified":"2024-03-10T03:07:31","modified_gmt":"2024-03-10T03:07:31","slug":"servicios-contables","status":"publish","type":"ignition-service","link":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/","title":{"rendered":"Servicios Contables"},"content":{"rendered":"\n<div class=\"guten-element guten-advanced-heading guten-2Prv9K\"><div class=\"heading-section outside-line\"><h3 class=\"heading-title\">Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles<span class=\"heading-focus\"><\/span><\/h3><\/div><span class=\"heading-subtitle\"><\/span><div class=\"heading-line bottom\"><\/div><\/div>\n\n\n\n<div class=\"guten-element gutenverse-text-editor guten-l8rWes\"><div class=\"text-content-inner\">\n<p class=\"wp-block-paragraph\">Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos, permiti\u00e9ndole tener tranquilidad y concentrarse en impulsar el crecimiento de su negocio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experiencia de nuestro equipo en el desarrollo de mejores pr\u00e1cticas le garantizar\u00e1 el cumplimiento de las normas contables vigentes tanto a nivel local como internacional. Adem\u00e1s, podemos ayudar con el cumplimiento tributario b\u00e1sico, que es obligatorio para todas las empresas en Colombia. Estamos comprometidos a brindarle un servicio oportuno y eficiente.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"guten-element guten-button-wrapper guten-4zkCIG\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/wpbc-booking\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span>Agendemos una cita<\/span><\/a><\/div>\n\n\n\n<div class=\"section-wrapper\" data-id=\"VQGQix\"><section class=\"wp-block-gutenverse-section guten-element guten-section guten-VQGQix layout-boxed align-stretch\"><div class=\"guten-background-overlay\"><\/div><div class=\"guten-shape-divider guten-shape-divider-top\"><\/div><div class=\"guten-shape-divider guten-shape-divider-bottom\"><\/div><div class=\"guten-container guten-column-gap-default\">\n<div class=\"wp-block-gutenverse-column guten-element guten-column guten-X4vzsA\"><div class=\"guten-background-overlay\"><\/div><div class=\"sticky-wrapper\" data-id=\"X4vzsA\"><div class=\"guten-column-wrapper\">\n<div class=\"guten-Yavqxa gutenverse-image-box guten-element style-default\"><div class=\"image-box-header\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><img decoding=\"async\" class=\"gutenverse-image-box-filled\" src=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/qtq_34.webp\" height=\"292\" width=\"388\"\/><\/a><\/div><div class=\"image-box-body\"><div class=\"body-inner\"><h3 class=\"body-title icon-position-before\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><i><\/i><span>Outsourcing o In house Contable e Impuestos B\u00e1sicos<\/span><\/a><\/h3><p class=\"body-description\">Nuestro objetivo es garantizar que nuestros clientes tengan la seguridad de que su informaci\u00f3n contable y financiera se procesa, analiza e interpreta con precisi\u00f3n. Esto no solo les permitir\u00e1 cumplir con los requisitos legales, sino que tambi\u00e9n les permitir\u00e1 tomar decisiones bien informadas y oportunas con respecto a su empresa.<br><br>Nuestros Servicios de Contabilidad e Impuestos abarcan varias etapas del proceso contable, que incluyen registrar y reconocer todas las transacciones diarias de la empresa, conciliar extractos bancarios y otras cuentas del balance, realizar los ajustes contables necesarios, preparar impuestos y hacer que un profesional fiscal los revise, crear estados financieros, y compartirlos con el gerente administrativo de la empresa.<\/p>\n<div class=\"guten-element guten-button-wrapper guten-lBrcv9\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/contact\/\"><span>Cont\u00e1ctenos<\/span><\/a><\/div>\n<div class=\"border-bottom\"><div class=\"animated left\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-gutenverse-column guten-element guten-column guten-zZDLMn\"><div class=\"guten-background-overlay\"><\/div><div class=\"sticky-wrapper\" data-id=\"zZDLMn\"><div class=\"guten-column-wrapper\">\n<div class=\"guten-mOLM6r gutenverse-image-box guten-element style-default\"><div class=\"image-box-header\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><img decoding=\"async\" class=\"gutenverse-image-box-filled\" src=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/qtq_34-1.webp\" height=\"292\" width=\"388\"\/><\/a><\/div><div class=\"image-box-body\"><div class=\"body-inner\"><h3 class=\"body-title icon-position-before\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><i><\/i><span>Integraci\u00f3n contable de m\u00faltiples compa\u00f1\u00edas o sucursales<\/span><\/a><\/h3><p class=\"body-description\">Tenemos la capacidad de preparar estados financieros combinados y consolidados, estandarizando varias monedas y pol\u00edticas contables, asegurando informaci\u00f3n oportuna para la toma de decisiones financieras informadas.<br><br>El objetivo principal es preparar estados financieros consolidados de acuerdo con las Normas Internacionales de Informaci\u00f3n Financiera, convertirlos a diversas monedas funcionales y lograr la estandarizaci\u00f3n de las pol\u00edticas contables.<\/p>\n<div class=\"guten-element guten-button-wrapper guten-l1h1ka\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/contact\/\"><span>Cont\u00e1ctenos<\/span><\/a><\/div>\n<div class=\"border-bottom\"><div class=\"animated left\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-gutenverse-column guten-element guten-column guten-go1vyd\"><div class=\"guten-background-overlay\"><\/div><div class=\"sticky-wrapper\" data-id=\"go1vyd\"><div class=\"guten-column-wrapper\">\n<div class=\"guten-UiN3nJ gutenverse-image-box guten-element style-default\"><div class=\"image-box-header\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><img decoding=\"async\" class=\"gutenverse-image-box-filled\" src=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/qtq_34-2.webp\" height=\"292\" width=\"388\"\/><\/a><\/div><div class=\"image-box-body\"><div class=\"body-inner\"><h3 class=\"body-title icon-position-before\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><i><\/i><span>Consultor\u00eda contable &#8211; Conceptos y aplicaci\u00f3n<\/span><\/a><\/h3><p class=\"body-description\">Como resultado del proceso de globalizaci\u00f3n, se ha vuelto cada vez m\u00e1s claro que implementar pol\u00edticas econ\u00f3micas abiertas y fomentar el intercambio comercial es de gran importancia. De manera similar, la estandarizaci\u00f3n de las pr\u00e1cticas y pol\u00edticas contables se ha convertido en un requisito necesario.<br><br>Hay cuestiones complejas y especializadas en la implementaci\u00f3n de las NIIF que requieren la experiencia de un profesional de servicios contables. Ofrecemos la preparaci\u00f3n de dichos conceptos, que pueden ser utilizados para m\u00faltiples objetivos, con personas certificadas y conocedoras que tienen experiencia en el estudio e implementaci\u00f3n de las NIIF.<\/p>\n<div class=\"guten-element guten-button-wrapper guten-fR13Bf\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/contact\/\"><span>Cont\u00e1ctenos<\/span><\/a><\/div>\n<div class=\"border-bottom\"><div class=\"animated left\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/section><\/div>\n\n\n\n<div class=\"section-wrapper\" data-id=\"8xErQM\"><section class=\"wp-block-gutenverse-section guten-element guten-section guten-8xErQM layout-boxed align-stretch\"><div class=\"guten-background-overlay\"><\/div><div class=\"guten-shape-divider guten-shape-divider-top\"><\/div><div class=\"guten-shape-divider guten-shape-divider-bottom\"><\/div><div class=\"guten-container guten-column-gap-default\">\n<div class=\"wp-block-gutenverse-column guten-element guten-column guten-got9rr\"><div class=\"guten-background-overlay\"><\/div><div class=\"sticky-wrapper\" data-id=\"got9rr\"><div class=\"guten-column-wrapper\">\n<div class=\"guten-WglD4u gutenverse-image-box guten-element style-default\"><div class=\"image-box-header\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><img decoding=\"async\" class=\"gutenverse-image-box-filled\" src=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/qtq_34-3.webp\" height=\"292\" width=\"388\"\/><\/a><\/div><div class=\"image-box-body\"><div class=\"body-inner\"><h3 class=\"body-title icon-position-before\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><i><\/i><span>Cumplimiento tributario nacional y municipal<\/span><\/a><\/h3><p class=\"body-description\">Nuestros Servicios Contables implican el manejo y examen minucioso de los impuestos nacionales o territoriales, priorizando la evaluaci\u00f3n de riesgos y el control tributario interno para garantizar certeza fiscal, minimizando as\u00ed la probabilidad de inexactitudes o descuidos en las declaraciones tributarias.\u200b<\/p>\n<div class=\"guten-element guten-button-wrapper guten-kNIwo6\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/contact\/\"><span>Cont\u00e1ctenos<\/span><\/a><\/div>\n<div class=\"border-bottom\"><div class=\"animated left\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-gutenverse-column guten-element guten-column guten-lphMRe\"><div class=\"guten-background-overlay\"><\/div><div class=\"sticky-wrapper\" data-id=\"lphMRe\"><div class=\"guten-column-wrapper\">\n<div class=\"guten-1Il3UM gutenverse-image-box guten-element style-default\"><div class=\"image-box-header\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><img decoding=\"async\" class=\"gutenverse-image-box-filled\" src=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/qtq_34-4.webp\" height=\"292\" width=\"388\"\/><\/a><\/div><div class=\"image-box-body\"><div class=\"body-inner\"><h3 class=\"body-title icon-position-before\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><i><\/i><span>Reportes a entidades de control<\/span><\/a><\/h3><p class=\"body-description\">Contamos con un equipo de expertos en Servicios Contables quienes se encargan de preparar estados financieros de acuerdo a diversas normas contables, realizar an\u00e1lisis contables para procesos de fusiones y adquisiciones, preparar estados financieros para periodos intermedios as\u00ed como brindar informaci\u00f3n financiera general.<\/p>\n<div class=\"guten-element guten-button-wrapper guten-FeijiS\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/contact\/\"><span>Cont\u00e1ctenos<\/span><\/a><\/div>\n<div class=\"border-bottom\"><div class=\"animated left\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-gutenverse-column guten-element guten-column guten-e0Jn1m\"><div class=\"guten-background-overlay\"><\/div><div class=\"sticky-wrapper\" data-id=\"e0Jn1m\"><div class=\"guten-column-wrapper\">\n<div class=\"guten-WmJEin gutenverse-image-box guten-element style-default\"><div class=\"image-box-header\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><img decoding=\"async\" class=\"gutenverse-image-box-filled\" src=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/qtq_34-5.webp\" height=\"292\" width=\"388\"\/><\/a><\/div><div class=\"image-box-body\"><div class=\"body-inner\"><h3 class=\"body-title icon-position-before\"><a class=\"\" href=\"https:\/\/sgh.com.co\/contact\/\"><i><\/i><span>Implementaci\u00f3n y migraci\u00f3n de software contable<\/span><\/a><\/h3><p class=\"body-description\">Somos capaces de ayudar con la parametrizaci\u00f3n de software contable y financiero para soportar procesos de negocio, as\u00ed como facilitar las migraciones de software entre diferentes sistemas y la realineaci\u00f3n de procesos para adaptarlos a nuevas tecnolog\u00edas.<\/p>\n<div class=\"guten-element guten-button-wrapper guten-csXqF2\"><a class=\"guten-button guten-button-sm\" href=\"https:\/\/sgh.com.co\/contact\/\"><span>Cont\u00e1ctenos<\/span><\/a><\/div>\n<div class=\"border-bottom\"><div class=\"animated left\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":232,"template":"","ignition_service_category":[],"class_list":["post-230","ignition-service","type-ignition-service","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicios Contables - Seven Group<\/title>\n<meta name=\"description\" content=\"Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgh.com.co\/servicio\/servicios-contables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios Contables - Seven Group\" \/>\n<meta property=\"og:description\" content=\"Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgh.com.co\/servicio\/servicios-contables\/\" \/>\n<meta property=\"og:site_name\" content=\"Seven Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/113153935426498\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-10T03:07:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/crw_600h_300-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/\",\"url\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/\",\"name\":\"Servicios Contables - Seven Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgh.com.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgh.com.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/crw_600h_300-2.webp\",\"datePublished\":\"2024-02-17T01:35:13+00:00\",\"dateModified\":\"2024-03-10T03:07:31+00:00\",\"description\":\"Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgh.com.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/crw_600h_300-2.webp\",\"contentUrl\":\"https:\\\/\\\/sgh.com.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/crw_600h_300-2.webp\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgh.com.co\\\/servicio\\\/servicios-contables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sgh.com.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios Contables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgh.com.co\\\/#website\",\"url\":\"https:\\\/\\\/sgh.com.co\\\/\",\"name\":\"Seven Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgh.com.co\\\/#organization\"},\"alternateName\":\"sgh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgh.com.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgh.com.co\\\/#organization\",\"name\":\"Seven Group\",\"alternateName\":\"SGH\",\"url\":\"https:\\\/\\\/sgh.com.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/sgh.com.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgh.com.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-Logopequeno-1.png\",\"contentUrl\":\"https:\\\/\\\/sgh.com.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-Logopequeno-1.png\",\"width\":511,\"height\":511,\"caption\":\"Seven Group\"},\"image\":{\"@id\":\"https:\\\/\\\/sgh.com.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/113153935426498\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seven-group-g7\\\/mycompany\\\/?viewAsMember=true\",\"https:\\\/\\\/wa.me\\\/573054388503\",\"https:\\\/\\\/www.instagram.com\\\/_7_group\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios Contables - Seven Group","description":"Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/","og_locale":"es_ES","og_type":"article","og_title":"Servicios Contables - Seven Group","og_description":"Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos,","og_url":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/","og_site_name":"Seven Group","article_publisher":"https:\/\/www.facebook.com\/113153935426498","article_modified_time":"2024-03-10T03:07:31+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/crw_600h_300-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/","url":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/","name":"Servicios Contables - Seven Group","isPartOf":{"@id":"https:\/\/sgh.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/#primaryimage"},"image":{"@id":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/#primaryimage"},"thumbnailUrl":"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/crw_600h_300-2.webp","datePublished":"2024-02-17T01:35:13+00:00","dateModified":"2024-03-10T03:07:31+00:00","description":"Reun\u00e1monos para mostrarle c\u00f3mo podemos servirles Este valioso servicio implica confiar sus necesidades contables a nuestro equipo de expertos,","breadcrumb":{"@id":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgh.com.co\/servicio\/servicios-contables\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/#primaryimage","url":"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/crw_600h_300-2.webp","contentUrl":"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/crw_600h_300-2.webp","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/sgh.com.co\/servicio\/servicios-contables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sgh.com.co\/"},{"@type":"ListItem","position":2,"name":"Servicios Contables"}]},{"@type":"WebSite","@id":"https:\/\/sgh.com.co\/#website","url":"https:\/\/sgh.com.co\/","name":"Seven Group","description":"","publisher":{"@id":"https:\/\/sgh.com.co\/#organization"},"alternateName":"sgh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgh.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/sgh.com.co\/#organization","name":"Seven Group","alternateName":"SGH","url":"https:\/\/sgh.com.co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/sgh.com.co\/#\/schema\/logo\/image\/","url":"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/cropped-cropped-Logopequeno-1.png","contentUrl":"https:\/\/sgh.com.co\/wp-content\/uploads\/2024\/02\/cropped-cropped-Logopequeno-1.png","width":511,"height":511,"caption":"Seven Group"},"image":{"@id":"https:\/\/sgh.com.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/113153935426498","https:\/\/www.linkedin.com\/company\/seven-group-g7\/mycompany\/?viewAsMember=true","https:\/\/wa.me\/573054388503","https:\/\/www.instagram.com\/_7_group\/"]}]}},"_links":{"self":[{"href":"https:\/\/sgh.com.co\/index.php\/wp-json\/wp\/v2\/ignition-service\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgh.com.co\/index.php\/wp-json\/wp\/v2\/ignition-service"}],"about":[{"href":"https:\/\/sgh.com.co\/index.php\/wp-json\/wp\/v2\/types\/ignition-service"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgh.com.co\/index.php\/wp-json\/wp\/v2\/media\/232"}],"wp:attachment":[{"href":"https:\/\/sgh.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=230"}],"wp:term":[{"taxonomy":"ignition_service_category","embeddable":true,"href":"https:\/\/sgh.com.co\/index.php\/wp-json\/wp\/v2\/ignition_service_category?post=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}